{"id":4414,"date":"2017-12-23T06:41:09","date_gmt":"2017-12-23T06:41:09","guid":{"rendered":"http:\/\/www.tomateros.com.mx\/?p=4414"},"modified":"2017-12-23T06:41:09","modified_gmt":"2017-12-23T06:41:09","slug":"gonzalez-caza-los-venados","status":"publish","type":"post","link":"https:\/\/web.tomateros.online\/index.php\/2017\/12\/23\/gonzalez-caza-los-venados\/","title":{"rendered":"GONZ\u00c1LEZ &#8216;CAZA&#8217; A LOS VENADOS"},"content":{"rendered":"<p><strong>Mazatl\u00e1n, Sinaloa a viernes 22 de diciembre de 2017.-<\/strong>. Magistral labor monticular de \u00c9dgar Gonz\u00e1lez, quien lanz\u00f3 juego completo para mantener a raya a la ofensiva de los Venados, a los que, gracias al respaldo de sus compa\u00f1eros, terminaron dobleg\u00e1ndolos al son de 8 carreras a 2.<\/p>\n<p>La \u00faltima vez que un guinda hab\u00eda tirado la ruta entera, hab\u00eda sido un 8 de diciembre de 2012 en que lo hizo Rodrigo L\u00f3pez quien curiosamente lo perdi\u00f3. Este fue el primer juego de este estilo de \u00c9dgar en 17 a\u00f1os de trayectoria.<\/p>\n<p>\u201cGracias a Dios se dieron las cosas, sin mis compa\u00f1eros no hubiera podido hacerlo, esas tremendas jugadas que hicieron a la defensiva y a la ofensiva que tambi\u00e9n batearon, permiti\u00f3 que se conjuntara todo y lo importante es que empezamos a lo grande aqu\u00ed en el puerto\u201d, comparti\u00f3 el regiomontano.<\/p>\n<p>Los Venados comenzaron el ataque en el tercer episodio en jonr\u00f3n de Brian Hern\u00e1ndez que se llev\u00f3 por delante a Niko Vasquez para ponerse al frente 2-0.<\/p>\n<p>El gusto no les dur\u00f3 mucho a los porte\u00f1os, pues en la siguiente entrada los guindas emparejaron el encuentro en sacrifly de Ryan McBroom al central con el que anot\u00f3 Rico Noel, mientras que Joey Meneses lo imit\u00f3 con misma jugada hacia esa direcci\u00f3n que permiti\u00f3 despegar al plato a Sebasti\u00e1n Elizalde para poner las cosas 2-2 por bando.<\/p>\n<p>En la sexta, los culichis continuaron haciendo de las suyas con par de registros; Ronier Mustelier peg\u00f3 hit al derecho anotando Antonio Lamas y Elizalde, McBroom intent\u00f3 irse hasta el pent\u00e1gono, pero fue puesto out, pero esto no evit\u00f3 que los capitalinos le dieran la voltereta al marcador 4-2.<\/p>\n<p>Fue en el octavo cap\u00edtulo en que los Tomateros volvieron a hacer da\u00f1o a sus adversarios con jugoso racimo de 4 carreras; McBroom produjo en imparable al izquierdo que mand\u00f3 a tierra prometida a Maxwell Le\u00f3n, enseguida Sebasti\u00e1n Elizalde timbr\u00f3 en pasaporte a Issmael Salas con los senderos hasta el tope y en sencillo de Ramiro Pe\u00f1a entraron par de anotaciones en los spikes de McBroom y Meneses para incrementar su delantera 8-2.<\/p>\n<p>\u00c9dgar Gonz\u00e1lez (3-3) se llev\u00f3 el contundente triunfo en 9 entradas de labor, en que le hicieron 7 hits, permiti\u00f3 2 carreras, no dio bases y ponch\u00f3 a 5 enemigos. Alejandro Soto se llev\u00f3 el descalabro (3-4).<\/p>\n<p>Para ma\u00f1ana, H\u00e9ctor Daniel Rodr\u00edguez regresa a la loma para enfrentarse a Francisco Moreno en punto de las 18:00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mazatl\u00e1n, Sinaloa a viernes 22 de diciembre de 2017.-. Magistral labor monticular de \u00c9dgar Gonz\u00e1lez, quien lanz\u00f3 juego completo para mantener a raya a la ofensiva de los Venados, a los que, gracias al respaldo de sus compa\u00f1eros, terminaron dobleg\u00e1ndolos al son de 8 carreras a 2. La \u00faltima vez que un guinda hab\u00eda tirado la ruta entera, hab\u00eda sido un 8 de diciembre de 2012 en que lo hizo Rodrigo L\u00f3pez quien curiosamente lo perdi\u00f3. Este fue el primer juego de este estilo de \u00c9dgar en 17 a\u00f1os de trayectoria. \u201cGracias a Dios se dieron las cosas, sin mis compa\u00f1eros no hubiera podido hacerlo, esas tremendas jugadas que hicieron a la defensiva y a la ofensiva que tambi\u00e9n batearon, permiti\u00f3 que se conjuntara todo y lo importante es que empezamos a lo grande aqu\u00ed en el puerto\u201d, comparti\u00f3 el regiomontano. Los Venados comenzaron el ataque en el tercer episodio en jonr\u00f3n de Brian Hern\u00e1ndez que se llev\u00f3 por delante a Niko Vasquez para ponerse al frente 2-0. El gusto no les dur\u00f3 mucho a los porte\u00f1os, pues en la siguiente entrada los guindas emparejaron el encuentro en sacrifly de Ryan McBroom al central con el que anot\u00f3 Rico Noel, mientras que Joey Meneses lo imit\u00f3 con misma jugada hacia esa direcci\u00f3n que permiti\u00f3 despegar al plato a Sebasti\u00e1n Elizalde para poner las cosas 2-2 por bando. En la sexta, los culichis continuaron haciendo de las suyas con par de registros; Ronier Mustelier peg\u00f3 hit al derecho anotando Antonio Lamas y Elizalde, McBroom intent\u00f3 irse hasta el pent\u00e1gono, pero fue puesto out, pero esto no evit\u00f3 que los capitalinos le dieran la voltereta al marcador 4-2. Fue en el octavo cap\u00edtulo en que los Tomateros volvieron a hacer da\u00f1o a sus adversarios con jugoso racimo de 4 carreras; McBroom produjo en imparable al izquierdo que mand\u00f3 a tierra prometida a Maxwell Le\u00f3n, enseguida Sebasti\u00e1n Elizalde timbr\u00f3 en pasaporte a Issmael Salas con los senderos hasta el tope y en sencillo de Ramiro Pe\u00f1a entraron par de anotaciones en los spikes de McBroom y Meneses para incrementar su delantera 8-2. \u00c9dgar Gonz\u00e1lez (3-3) se llev\u00f3 el contundente triunfo en 9 entradas de labor, en que le hicieron 7 hits, permiti\u00f3 2 carreras, no dio bases y ponch\u00f3 a 5 enemigos. Alejandro Soto se llev\u00f3 el descalabro (3-4). Para ma\u00f1ana, H\u00e9ctor Daniel Rodr\u00edguez regresa a la loma para enfrentarse a Francisco Moreno en punto de las 18:00 horas.<\/p>\n","protected":false},"author":1,"featured_media":4415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/posts\/4414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/comments?post=4414"}],"version-history":[{"count":0,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/posts\/4414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/media\/4415"}],"wp:attachment":[{"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/media?parent=4414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/categories?post=4414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.tomateros.online\/index.php\/wp-json\/wp\/v2\/tags?post=4414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}